{"id":4680,"date":"2022-05-12T09:52:04","date_gmt":"2022-05-12T07:52:04","guid":{"rendered":"https:\/\/www.zaccantispa.it\/?p=4680"},"modified":"2022-05-12T09:52:04","modified_gmt":"2022-05-12T07:52:04","slug":"27th-may-riccione-emergency-minimally-invasive-surgery-how-far-have-we-come","status":"publish","type":"post","link":"https:\/\/www.zaccantispa.it\/de\/eventi-de\/27th-may-riccione-emergency-minimally-invasive-surgery-how-far-have-we-come\/","title":{"rendered":"27th May, Riccione &#8211; Emergency minimally invasive surgery: How far have we come?"},"content":{"rendered":"<p><a href=\"https:\/\/www.zaccantispa.it\/wp-content\/uploads\/2022\/05\/EMERGENCY-MINIMALLY-INVASIVE-SURGERY.pdf\">View program<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>View program<\/p>\n","protected":false},"author":1,"featured_media":4675,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[73,74,54],"class_list":["post-4680","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi-de","tag-fegato-de","tag-mils-de","tag-scuola-de"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>27th May, Riccione - Emergency minimally invasive surgery: How far have we come? - Zaccanti S.p.A.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.zaccantispa.it\/de\/eventi-de\/27th-may-riccione-emergency-minimally-invasive-surgery-how-far-have-we-come\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"27th May, Riccione - Emergency minimally invasive surgery: How far have we come? - Zaccanti S.p.A.\" \/>\n<meta property=\"og:description\" content=\"View program\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.zaccantispa.it\/de\/eventi-de\/27th-may-riccione-emergency-minimally-invasive-surgery-how-far-have-we-come\/\" \/>\n<meta property=\"og:site_name\" content=\"Zaccanti S.p.A.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ZaccantiSpABologna\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-12T07:52:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.zaccantispa.it\/wp-content\/uploads\/2022\/05\/EMERGENCY-MINIMALLY-INVASIVE-SURGERY.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"793\" \/>\n\t<meta property=\"og:image:height\" content=\"534\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/de\\\/eventi-de\\\/27th-may-riccione-emergency-minimally-invasive-surgery-how-far-have-we-come\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/de\\\/eventi-de\\\/27th-may-riccione-emergency-minimally-invasive-surgery-how-far-have-we-come\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/#\\\/schema\\\/person\\\/3b208f4728979a25b0d47e46d7b9d222\"},\"headline\":\"27th May, Riccione &#8211; Emergency minimally invasive surgery: How far have we come?\",\"datePublished\":\"2022-05-12T07:52:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/de\\\/eventi-de\\\/27th-may-riccione-emergency-minimally-invasive-surgery-how-far-have-we-come\\\/\"},\"wordCount\":15,\"publisher\":{\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/de\\\/eventi-de\\\/27th-may-riccione-emergency-minimally-invasive-surgery-how-far-have-we-come\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zaccantispa.it\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/EMERGENCY-MINIMALLY-INVASIVE-SURGERY.jpg\",\"keywords\":[\"fegato\",\"mils\",\"scuola\"],\"articleSection\":[\"Eventi\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/de\\\/eventi-de\\\/27th-may-riccione-emergency-minimally-invasive-surgery-how-far-have-we-come\\\/\",\"url\":\"https:\\\/\\\/www.zaccantispa.it\\\/de\\\/eventi-de\\\/27th-may-riccione-emergency-minimally-invasive-surgery-how-far-have-we-come\\\/\",\"name\":\"27th May, Riccione - Emergency minimally invasive surgery: How far have we come? - Zaccanti S.p.A.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/de\\\/eventi-de\\\/27th-may-riccione-emergency-minimally-invasive-surgery-how-far-have-we-come\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/de\\\/eventi-de\\\/27th-may-riccione-emergency-minimally-invasive-surgery-how-far-have-we-come\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zaccantispa.it\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/EMERGENCY-MINIMALLY-INVASIVE-SURGERY.jpg\",\"datePublished\":\"2022-05-12T07:52:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/de\\\/eventi-de\\\/27th-may-riccione-emergency-minimally-invasive-surgery-how-far-have-we-come\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.zaccantispa.it\\\/de\\\/eventi-de\\\/27th-may-riccione-emergency-minimally-invasive-surgery-how-far-have-we-come\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/de\\\/eventi-de\\\/27th-may-riccione-emergency-minimally-invasive-surgery-how-far-have-we-come\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.zaccantispa.it\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/EMERGENCY-MINIMALLY-INVASIVE-SURGERY.jpg\",\"contentUrl\":\"https:\\\/\\\/www.zaccantispa.it\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/EMERGENCY-MINIMALLY-INVASIVE-SURGERY.jpg\",\"width\":793,\"height\":534},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/de\\\/eventi-de\\\/27th-may-riccione-emergency-minimally-invasive-surgery-how-far-have-we-come\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.zaccantispa.it\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"27th May, Riccione &#8211; Emergency minimally invasive surgery: How far have we come?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/\",\"name\":\"Zaccanti S.p.A.\",\"description\":\"La chirurgia esplora nuovi mondi\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/#organization\",\"name\":\"Zaccanti s.p.a.\",\"url\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.zaccantispa.it\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-2024-02-14-Zaccanti-Bocchetti-Group-70-1954-2024-su-fondo-bianco-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.zaccantispa.it\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-2024-02-14-Zaccanti-Bocchetti-Group-70-1954-2024-su-fondo-bianco-logo.png\",\"width\":512,\"height\":512,\"caption\":\"Zaccanti s.p.a.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ZaccantiSpABologna\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/zaccanti-s-p-a\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/#\\\/schema\\\/person\\\/3b208f4728979a25b0d47e46d7b9d222\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cb509eb6c091c3da64982812cd5189030e59b0d67219720a307a30a4f8d67560?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cb509eb6c091c3da64982812cd5189030e59b0d67219720a307a30a4f8d67560?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cb509eb6c091c3da64982812cd5189030e59b0d67219720a307a30a4f8d67560?s=96&d=mm&r=g\",\"caption\":\"admin\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"27th May, Riccione - Emergency minimally invasive surgery: How far have we come? - Zaccanti S.p.A.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.zaccantispa.it\/de\/eventi-de\/27th-may-riccione-emergency-minimally-invasive-surgery-how-far-have-we-come\/","og_locale":"de_DE","og_type":"article","og_title":"27th May, Riccione - Emergency minimally invasive surgery: How far have we come? - Zaccanti S.p.A.","og_description":"View program","og_url":"https:\/\/www.zaccantispa.it\/de\/eventi-de\/27th-may-riccione-emergency-minimally-invasive-surgery-how-far-have-we-come\/","og_site_name":"Zaccanti S.p.A.","article_publisher":"https:\/\/www.facebook.com\/ZaccantiSpABologna","article_published_time":"2022-05-12T07:52:04+00:00","og_image":[{"width":793,"height":534,"url":"https:\/\/www.zaccantispa.it\/wp-content\/uploads\/2022\/05\/EMERGENCY-MINIMALLY-INVASIVE-SURGERY.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"admin","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.zaccantispa.it\/de\/eventi-de\/27th-may-riccione-emergency-minimally-invasive-surgery-how-far-have-we-come\/#article","isPartOf":{"@id":"https:\/\/www.zaccantispa.it\/de\/eventi-de\/27th-may-riccione-emergency-minimally-invasive-surgery-how-far-have-we-come\/"},"author":{"name":"admin","@id":"https:\/\/www.zaccantispa.it\/en\/#\/schema\/person\/3b208f4728979a25b0d47e46d7b9d222"},"headline":"27th May, Riccione &#8211; Emergency minimally invasive surgery: How far have we come?","datePublished":"2022-05-12T07:52:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.zaccantispa.it\/de\/eventi-de\/27th-may-riccione-emergency-minimally-invasive-surgery-how-far-have-we-come\/"},"wordCount":15,"publisher":{"@id":"https:\/\/www.zaccantispa.it\/en\/#organization"},"image":{"@id":"https:\/\/www.zaccantispa.it\/de\/eventi-de\/27th-may-riccione-emergency-minimally-invasive-surgery-how-far-have-we-come\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zaccantispa.it\/wp-content\/uploads\/2022\/05\/EMERGENCY-MINIMALLY-INVASIVE-SURGERY.jpg","keywords":["fegato","mils","scuola"],"articleSection":["Eventi"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.zaccantispa.it\/de\/eventi-de\/27th-may-riccione-emergency-minimally-invasive-surgery-how-far-have-we-come\/","url":"https:\/\/www.zaccantispa.it\/de\/eventi-de\/27th-may-riccione-emergency-minimally-invasive-surgery-how-far-have-we-come\/","name":"27th May, Riccione - Emergency minimally invasive surgery: How far have we come? - Zaccanti S.p.A.","isPartOf":{"@id":"https:\/\/www.zaccantispa.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.zaccantispa.it\/de\/eventi-de\/27th-may-riccione-emergency-minimally-invasive-surgery-how-far-have-we-come\/#primaryimage"},"image":{"@id":"https:\/\/www.zaccantispa.it\/de\/eventi-de\/27th-may-riccione-emergency-minimally-invasive-surgery-how-far-have-we-come\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zaccantispa.it\/wp-content\/uploads\/2022\/05\/EMERGENCY-MINIMALLY-INVASIVE-SURGERY.jpg","datePublished":"2022-05-12T07:52:04+00:00","breadcrumb":{"@id":"https:\/\/www.zaccantispa.it\/de\/eventi-de\/27th-may-riccione-emergency-minimally-invasive-surgery-how-far-have-we-come\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.zaccantispa.it\/de\/eventi-de\/27th-may-riccione-emergency-minimally-invasive-surgery-how-far-have-we-come\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.zaccantispa.it\/de\/eventi-de\/27th-may-riccione-emergency-minimally-invasive-surgery-how-far-have-we-come\/#primaryimage","url":"https:\/\/www.zaccantispa.it\/wp-content\/uploads\/2022\/05\/EMERGENCY-MINIMALLY-INVASIVE-SURGERY.jpg","contentUrl":"https:\/\/www.zaccantispa.it\/wp-content\/uploads\/2022\/05\/EMERGENCY-MINIMALLY-INVASIVE-SURGERY.jpg","width":793,"height":534},{"@type":"BreadcrumbList","@id":"https:\/\/www.zaccantispa.it\/de\/eventi-de\/27th-may-riccione-emergency-minimally-invasive-surgery-how-far-have-we-come\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.zaccantispa.it\/de\/"},{"@type":"ListItem","position":2,"name":"27th May, Riccione &#8211; Emergency minimally invasive surgery: How far have we come?"}]},{"@type":"WebSite","@id":"https:\/\/www.zaccantispa.it\/en\/#website","url":"https:\/\/www.zaccantispa.it\/en\/","name":"Zaccanti S.p.A.","description":"La chirurgia esplora nuovi mondi","publisher":{"@id":"https:\/\/www.zaccantispa.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.zaccantispa.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.zaccantispa.it\/en\/#organization","name":"Zaccanti s.p.a.","url":"https:\/\/www.zaccantispa.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.zaccantispa.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.zaccantispa.it\/wp-content\/uploads\/2024\/05\/cropped-2024-02-14-Zaccanti-Bocchetti-Group-70-1954-2024-su-fondo-bianco-logo.png","contentUrl":"https:\/\/www.zaccantispa.it\/wp-content\/uploads\/2024\/05\/cropped-2024-02-14-Zaccanti-Bocchetti-Group-70-1954-2024-su-fondo-bianco-logo.png","width":512,"height":512,"caption":"Zaccanti s.p.a."},"image":{"@id":"https:\/\/www.zaccantispa.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ZaccantiSpABologna","https:\/\/www.linkedin.com\/company\/zaccanti-s-p-a\/"]},{"@type":"Person","@id":"https:\/\/www.zaccantispa.it\/en\/#\/schema\/person\/3b208f4728979a25b0d47e46d7b9d222","name":"admin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/cb509eb6c091c3da64982812cd5189030e59b0d67219720a307a30a4f8d67560?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cb509eb6c091c3da64982812cd5189030e59b0d67219720a307a30a4f8d67560?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cb509eb6c091c3da64982812cd5189030e59b0d67219720a307a30a4f8d67560?s=96&d=mm&r=g","caption":"admin"}}]}},"_links":{"self":[{"href":"https:\/\/www.zaccantispa.it\/de\/wp-json\/wp\/v2\/posts\/4680","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zaccantispa.it\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zaccantispa.it\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zaccantispa.it\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zaccantispa.it\/de\/wp-json\/wp\/v2\/comments?post=4680"}],"version-history":[{"count":1,"href":"https:\/\/www.zaccantispa.it\/de\/wp-json\/wp\/v2\/posts\/4680\/revisions"}],"predecessor-version":[{"id":4684,"href":"https:\/\/www.zaccantispa.it\/de\/wp-json\/wp\/v2\/posts\/4680\/revisions\/4684"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zaccantispa.it\/de\/wp-json\/wp\/v2\/media\/4675"}],"wp:attachment":[{"href":"https:\/\/www.zaccantispa.it\/de\/wp-json\/wp\/v2\/media?parent=4680"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zaccantispa.it\/de\/wp-json\/wp\/v2\/categories?post=4680"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zaccantispa.it\/de\/wp-json\/wp\/v2\/tags?post=4680"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}