{"id":2721,"date":"2019-01-08T17:59:13","date_gmt":"2019-01-08T16:59:13","guid":{"rendered":"http:\/\/www.zaccantispa.it\/uncategorized\/eras-cosa-ce-di-nuovo-conegliano-18-gennaio-2019\/"},"modified":"2019-01-24T16:03:38","modified_gmt":"2019-01-24T15:03:38","slug":"eras-cosa-ce-di-nuovo-conegliano-18-gennaio-2019","status":"publish","type":"post","link":"https:\/\/www.zaccantispa.it\/en\/eventi-en\/eras-cosa-ce-di-nuovo-conegliano-18-gennaio-2019\/","title":{"rendered":"Eras: cosa c&#8217;\u00e8 di nuovo? &#8211; Conegliano &#8211; 18 gennaio 2019"},"content":{"rendered":"<p><a href=\"http:\/\/www.zaccantispa.it\/wp-content\/uploads\/2019\/01\/2019-ERAS-Corretto1_LOW.pdf\">Visualizza il programma<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Visualizza il programma<\/p>\n","protected":false},"author":1,"featured_media":2567,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-2721","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi-en"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Eras: cosa c&#039;\u00e8 di nuovo? - Conegliano - 18 gennaio 2019 - Zaccanti S.p.A.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.zaccantispa.it\/en\/eventi-en\/eras-cosa-ce-di-nuovo-conegliano-18-gennaio-2019\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eras: cosa c&#039;\u00e8 di nuovo? - Conegliano - 18 gennaio 2019 - Zaccanti S.p.A.\" \/>\n<meta property=\"og:description\" content=\"Visualizza il programma\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.zaccantispa.it\/en\/eventi-en\/eras-cosa-ce-di-nuovo-conegliano-18-gennaio-2019\/\" \/>\n<meta property=\"og:site_name\" content=\"Zaccanti S.p.A.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ZaccantiSpABologna\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-08T16:59:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-01-24T15:03:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.zaccantispa.it\/wp-content\/uploads\/2019\/01\/2019-ERAS-Corretto1_LOW-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1181\" \/>\n\t<meta property=\"og:image:height\" content=\"838\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/eventi-en\\\/eras-cosa-ce-di-nuovo-conegliano-18-gennaio-2019\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/eventi-en\\\/eras-cosa-ce-di-nuovo-conegliano-18-gennaio-2019\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/#\\\/schema\\\/person\\\/3b208f4728979a25b0d47e46d7b9d222\"},\"headline\":\"Eras: cosa c&#8217;\u00e8 di nuovo? &#8211; Conegliano &#8211; 18 gennaio 2019\",\"datePublished\":\"2019-01-08T16:59:13+00:00\",\"dateModified\":\"2019-01-24T15:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/eventi-en\\\/eras-cosa-ce-di-nuovo-conegliano-18-gennaio-2019\\\/\"},\"wordCount\":12,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/eventi-en\\\/eras-cosa-ce-di-nuovo-conegliano-18-gennaio-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zaccantispa.it\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/2019-ERAS-Corretto1_LOW-1.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/eventi-en\\\/eras-cosa-ce-di-nuovo-conegliano-18-gennaio-2019\\\/\",\"url\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/eventi-en\\\/eras-cosa-ce-di-nuovo-conegliano-18-gennaio-2019\\\/\",\"name\":\"Eras: cosa c'\u00e8 di nuovo? - Conegliano - 18 gennaio 2019 - Zaccanti S.p.A.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/eventi-en\\\/eras-cosa-ce-di-nuovo-conegliano-18-gennaio-2019\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/eventi-en\\\/eras-cosa-ce-di-nuovo-conegliano-18-gennaio-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zaccantispa.it\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/2019-ERAS-Corretto1_LOW-1.jpg\",\"datePublished\":\"2019-01-08T16:59:13+00:00\",\"dateModified\":\"2019-01-24T15:03:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/eventi-en\\\/eras-cosa-ce-di-nuovo-conegliano-18-gennaio-2019\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/eventi-en\\\/eras-cosa-ce-di-nuovo-conegliano-18-gennaio-2019\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/eventi-en\\\/eras-cosa-ce-di-nuovo-conegliano-18-gennaio-2019\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.zaccantispa.it\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/2019-ERAS-Corretto1_LOW-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.zaccantispa.it\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/2019-ERAS-Corretto1_LOW-1.jpg\",\"width\":1181,\"height\":838},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/eventi-en\\\/eras-cosa-ce-di-nuovo-conegliano-18-gennaio-2019\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eras: cosa c&#8217;\u00e8 di nuovo? &#8211; Conegliano &#8211; 18 gennaio 2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/\",\"name\":\"Zaccanti S.p.A.\",\"description\":\"La chirurgia esplora nuovi mondi\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/#organization\",\"name\":\"Zaccanti s.p.a.\",\"url\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.zaccantispa.it\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-2024-02-14-Zaccanti-Bocchetti-Group-70-1954-2024-su-fondo-bianco-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.zaccantispa.it\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-2024-02-14-Zaccanti-Bocchetti-Group-70-1954-2024-su-fondo-bianco-logo.png\",\"width\":512,\"height\":512,\"caption\":\"Zaccanti s.p.a.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ZaccantiSpABologna\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/zaccanti-s-p-a\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/#\\\/schema\\\/person\\\/3b208f4728979a25b0d47e46d7b9d222\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cb509eb6c091c3da64982812cd5189030e59b0d67219720a307a30a4f8d67560?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cb509eb6c091c3da64982812cd5189030e59b0d67219720a307a30a4f8d67560?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cb509eb6c091c3da64982812cd5189030e59b0d67219720a307a30a4f8d67560?s=96&d=mm&r=g\",\"caption\":\"admin\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Eras: cosa c'\u00e8 di nuovo? - Conegliano - 18 gennaio 2019 - Zaccanti S.p.A.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.zaccantispa.it\/en\/eventi-en\/eras-cosa-ce-di-nuovo-conegliano-18-gennaio-2019\/","og_locale":"en_US","og_type":"article","og_title":"Eras: cosa c'\u00e8 di nuovo? - Conegliano - 18 gennaio 2019 - Zaccanti S.p.A.","og_description":"Visualizza il programma","og_url":"https:\/\/www.zaccantispa.it\/en\/eventi-en\/eras-cosa-ce-di-nuovo-conegliano-18-gennaio-2019\/","og_site_name":"Zaccanti S.p.A.","article_publisher":"https:\/\/www.facebook.com\/ZaccantiSpABologna","article_published_time":"2019-01-08T16:59:13+00:00","article_modified_time":"2019-01-24T15:03:38+00:00","og_image":[{"width":1181,"height":838,"url":"https:\/\/www.zaccantispa.it\/wp-content\/uploads\/2019\/01\/2019-ERAS-Corretto1_LOW-1.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.zaccantispa.it\/en\/eventi-en\/eras-cosa-ce-di-nuovo-conegliano-18-gennaio-2019\/#article","isPartOf":{"@id":"https:\/\/www.zaccantispa.it\/en\/eventi-en\/eras-cosa-ce-di-nuovo-conegliano-18-gennaio-2019\/"},"author":{"name":"admin","@id":"https:\/\/www.zaccantispa.it\/en\/#\/schema\/person\/3b208f4728979a25b0d47e46d7b9d222"},"headline":"Eras: cosa c&#8217;\u00e8 di nuovo? &#8211; Conegliano &#8211; 18 gennaio 2019","datePublished":"2019-01-08T16:59:13+00:00","dateModified":"2019-01-24T15:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.zaccantispa.it\/en\/eventi-en\/eras-cosa-ce-di-nuovo-conegliano-18-gennaio-2019\/"},"wordCount":12,"commentCount":0,"publisher":{"@id":"https:\/\/www.zaccantispa.it\/en\/#organization"},"image":{"@id":"https:\/\/www.zaccantispa.it\/en\/eventi-en\/eras-cosa-ce-di-nuovo-conegliano-18-gennaio-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zaccantispa.it\/wp-content\/uploads\/2019\/01\/2019-ERAS-Corretto1_LOW-1.jpg","articleSection":["Eventi"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.zaccantispa.it\/en\/eventi-en\/eras-cosa-ce-di-nuovo-conegliano-18-gennaio-2019\/","url":"https:\/\/www.zaccantispa.it\/en\/eventi-en\/eras-cosa-ce-di-nuovo-conegliano-18-gennaio-2019\/","name":"Eras: cosa c'\u00e8 di nuovo? - Conegliano - 18 gennaio 2019 - Zaccanti S.p.A.","isPartOf":{"@id":"https:\/\/www.zaccantispa.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.zaccantispa.it\/en\/eventi-en\/eras-cosa-ce-di-nuovo-conegliano-18-gennaio-2019\/#primaryimage"},"image":{"@id":"https:\/\/www.zaccantispa.it\/en\/eventi-en\/eras-cosa-ce-di-nuovo-conegliano-18-gennaio-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zaccantispa.it\/wp-content\/uploads\/2019\/01\/2019-ERAS-Corretto1_LOW-1.jpg","datePublished":"2019-01-08T16:59:13+00:00","dateModified":"2019-01-24T15:03:38+00:00","breadcrumb":{"@id":"https:\/\/www.zaccantispa.it\/en\/eventi-en\/eras-cosa-ce-di-nuovo-conegliano-18-gennaio-2019\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.zaccantispa.it\/en\/eventi-en\/eras-cosa-ce-di-nuovo-conegliano-18-gennaio-2019\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.zaccantispa.it\/en\/eventi-en\/eras-cosa-ce-di-nuovo-conegliano-18-gennaio-2019\/#primaryimage","url":"https:\/\/www.zaccantispa.it\/wp-content\/uploads\/2019\/01\/2019-ERAS-Corretto1_LOW-1.jpg","contentUrl":"https:\/\/www.zaccantispa.it\/wp-content\/uploads\/2019\/01\/2019-ERAS-Corretto1_LOW-1.jpg","width":1181,"height":838},{"@type":"BreadcrumbList","@id":"https:\/\/www.zaccantispa.it\/en\/eventi-en\/eras-cosa-ce-di-nuovo-conegliano-18-gennaio-2019\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.zaccantispa.it\/en\/"},{"@type":"ListItem","position":2,"name":"Eras: cosa c&#8217;\u00e8 di nuovo? &#8211; Conegliano &#8211; 18 gennaio 2019"}]},{"@type":"WebSite","@id":"https:\/\/www.zaccantispa.it\/en\/#website","url":"https:\/\/www.zaccantispa.it\/en\/","name":"Zaccanti S.p.A.","description":"La chirurgia esplora nuovi mondi","publisher":{"@id":"https:\/\/www.zaccantispa.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.zaccantispa.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.zaccantispa.it\/en\/#organization","name":"Zaccanti s.p.a.","url":"https:\/\/www.zaccantispa.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.zaccantispa.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.zaccantispa.it\/wp-content\/uploads\/2024\/05\/cropped-2024-02-14-Zaccanti-Bocchetti-Group-70-1954-2024-su-fondo-bianco-logo.png","contentUrl":"https:\/\/www.zaccantispa.it\/wp-content\/uploads\/2024\/05\/cropped-2024-02-14-Zaccanti-Bocchetti-Group-70-1954-2024-su-fondo-bianco-logo.png","width":512,"height":512,"caption":"Zaccanti s.p.a."},"image":{"@id":"https:\/\/www.zaccantispa.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ZaccantiSpABologna","https:\/\/www.linkedin.com\/company\/zaccanti-s-p-a\/"]},{"@type":"Person","@id":"https:\/\/www.zaccantispa.it\/en\/#\/schema\/person\/3b208f4728979a25b0d47e46d7b9d222","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/cb509eb6c091c3da64982812cd5189030e59b0d67219720a307a30a4f8d67560?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cb509eb6c091c3da64982812cd5189030e59b0d67219720a307a30a4f8d67560?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cb509eb6c091c3da64982812cd5189030e59b0d67219720a307a30a4f8d67560?s=96&d=mm&r=g","caption":"admin"}}]}},"_links":{"self":[{"href":"https:\/\/www.zaccantispa.it\/en\/wp-json\/wp\/v2\/posts\/2721","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zaccantispa.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zaccantispa.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zaccantispa.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zaccantispa.it\/en\/wp-json\/wp\/v2\/comments?post=2721"}],"version-history":[{"count":1,"href":"https:\/\/www.zaccantispa.it\/en\/wp-json\/wp\/v2\/posts\/2721\/revisions"}],"predecessor-version":[{"id":2722,"href":"https:\/\/www.zaccantispa.it\/en\/wp-json\/wp\/v2\/posts\/2721\/revisions\/2722"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zaccantispa.it\/en\/wp-json\/wp\/v2\/media\/2567"}],"wp:attachment":[{"href":"https:\/\/www.zaccantispa.it\/en\/wp-json\/wp\/v2\/media?parent=2721"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zaccantispa.it\/en\/wp-json\/wp\/v2\/categories?post=2721"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zaccantispa.it\/en\/wp-json\/wp\/v2\/tags?post=2721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}