{"id":2745,"date":"2018-03-31T16:19:21","date_gmt":"2018-03-31T14:19:21","guid":{"rendered":"http:\/\/www.zaccantispa.it\/uncategorized\/la-patologia-pelvica-funzionale-femminile-ferrara-26-27-gennaio-2018\/"},"modified":"2019-01-24T16:16:57","modified_gmt":"2019-01-24T15:16:57","slug":"la-patologia-pelvica-funzionale-femminile-ferrara-26-27-gennaio-2018","status":"publish","type":"post","link":"https:\/\/www.zaccantispa.it\/en\/eventi-en\/la-patologia-pelvica-funzionale-femminile-ferrara-26-27-gennaio-2018\/","title":{"rendered":"La patologia pelvica funzionale femminile &#8211; Ferrara &#8211; 26-27 gennaio 2018"},"content":{"rendered":"<p><a href=\"http:\/\/www.zaccantispa.it\/wp-content\/uploads\/2018\/05\/2017-078-programma-DEFINITIVO.pdf\">Clicca qui per leggere il programma.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Clicca qui per leggere il programma.<\/p>\n","protected":false},"author":1,"featured_media":1266,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-2745","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi-en"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La patologia pelvica funzionale femminile - Ferrara - 26-27 gennaio 2018 - Zaccanti S.p.A.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.zaccantispa.it\/en\/eventi-en\/la-patologia-pelvica-funzionale-femminile-ferrara-26-27-gennaio-2018\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La patologia pelvica funzionale femminile - Ferrara - 26-27 gennaio 2018 - Zaccanti S.p.A.\" \/>\n<meta property=\"og:description\" content=\"Clicca qui per leggere il programma.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.zaccantispa.it\/en\/eventi-en\/la-patologia-pelvica-funzionale-femminile-ferrara-26-27-gennaio-2018\/\" \/>\n<meta property=\"og:site_name\" content=\"Zaccanti S.p.A.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ZaccantiSpABologna\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-31T14:19:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-01-24T15:16:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.zaccantispa.it\/wp-content\/uploads\/2018\/03\/ferrara01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"745\" \/>\n\t<meta property=\"og:image:height\" content=\"745\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/eventi-en\\\/la-patologia-pelvica-funzionale-femminile-ferrara-26-27-gennaio-2018\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/eventi-en\\\/la-patologia-pelvica-funzionale-femminile-ferrara-26-27-gennaio-2018\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/#\\\/schema\\\/person\\\/3b208f4728979a25b0d47e46d7b9d222\"},\"headline\":\"La patologia pelvica funzionale femminile &#8211; Ferrara &#8211; 26-27 gennaio 2018\",\"datePublished\":\"2018-03-31T14:19:21+00:00\",\"dateModified\":\"2019-01-24T15:16:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/eventi-en\\\/la-patologia-pelvica-funzionale-femminile-ferrara-26-27-gennaio-2018\\\/\"},\"wordCount\":16,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/eventi-en\\\/la-patologia-pelvica-funzionale-femminile-ferrara-26-27-gennaio-2018\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zaccantispa.it\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/ferrara01.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/eventi-en\\\/la-patologia-pelvica-funzionale-femminile-ferrara-26-27-gennaio-2018\\\/\",\"url\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/eventi-en\\\/la-patologia-pelvica-funzionale-femminile-ferrara-26-27-gennaio-2018\\\/\",\"name\":\"La patologia pelvica funzionale femminile - Ferrara - 26-27 gennaio 2018 - Zaccanti S.p.A.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/eventi-en\\\/la-patologia-pelvica-funzionale-femminile-ferrara-26-27-gennaio-2018\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/eventi-en\\\/la-patologia-pelvica-funzionale-femminile-ferrara-26-27-gennaio-2018\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zaccantispa.it\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/ferrara01.jpg\",\"datePublished\":\"2018-03-31T14:19:21+00:00\",\"dateModified\":\"2019-01-24T15:16:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/eventi-en\\\/la-patologia-pelvica-funzionale-femminile-ferrara-26-27-gennaio-2018\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/eventi-en\\\/la-patologia-pelvica-funzionale-femminile-ferrara-26-27-gennaio-2018\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/eventi-en\\\/la-patologia-pelvica-funzionale-femminile-ferrara-26-27-gennaio-2018\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.zaccantispa.it\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/ferrara01.jpg\",\"contentUrl\":\"https:\\\/\\\/www.zaccantispa.it\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/ferrara01.jpg\",\"width\":745,\"height\":745},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/eventi-en\\\/la-patologia-pelvica-funzionale-femminile-ferrara-26-27-gennaio-2018\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La patologia pelvica funzionale femminile &#8211; Ferrara &#8211; 26-27 gennaio 2018\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/\",\"name\":\"Zaccanti S.p.A.\",\"description\":\"La chirurgia esplora nuovi mondi\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/#organization\",\"name\":\"Zaccanti s.p.a.\",\"url\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.zaccantispa.it\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-2024-02-14-Zaccanti-Bocchetti-Group-70-1954-2024-su-fondo-bianco-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.zaccantispa.it\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-2024-02-14-Zaccanti-Bocchetti-Group-70-1954-2024-su-fondo-bianco-logo.png\",\"width\":512,\"height\":512,\"caption\":\"Zaccanti s.p.a.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ZaccantiSpABologna\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/zaccanti-s-p-a\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/#\\\/schema\\\/person\\\/3b208f4728979a25b0d47e46d7b9d222\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cb509eb6c091c3da64982812cd5189030e59b0d67219720a307a30a4f8d67560?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cb509eb6c091c3da64982812cd5189030e59b0d67219720a307a30a4f8d67560?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cb509eb6c091c3da64982812cd5189030e59b0d67219720a307a30a4f8d67560?s=96&d=mm&r=g\",\"caption\":\"admin\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La patologia pelvica funzionale femminile - Ferrara - 26-27 gennaio 2018 - Zaccanti S.p.A.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.zaccantispa.it\/en\/eventi-en\/la-patologia-pelvica-funzionale-femminile-ferrara-26-27-gennaio-2018\/","og_locale":"en_US","og_type":"article","og_title":"La patologia pelvica funzionale femminile - Ferrara - 26-27 gennaio 2018 - Zaccanti S.p.A.","og_description":"Clicca qui per leggere il programma.","og_url":"https:\/\/www.zaccantispa.it\/en\/eventi-en\/la-patologia-pelvica-funzionale-femminile-ferrara-26-27-gennaio-2018\/","og_site_name":"Zaccanti S.p.A.","article_publisher":"https:\/\/www.facebook.com\/ZaccantiSpABologna","article_published_time":"2018-03-31T14:19:21+00:00","article_modified_time":"2019-01-24T15:16:57+00:00","og_image":[{"width":745,"height":745,"url":"https:\/\/www.zaccantispa.it\/wp-content\/uploads\/2018\/03\/ferrara01.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.zaccantispa.it\/en\/eventi-en\/la-patologia-pelvica-funzionale-femminile-ferrara-26-27-gennaio-2018\/#article","isPartOf":{"@id":"https:\/\/www.zaccantispa.it\/en\/eventi-en\/la-patologia-pelvica-funzionale-femminile-ferrara-26-27-gennaio-2018\/"},"author":{"name":"admin","@id":"https:\/\/www.zaccantispa.it\/en\/#\/schema\/person\/3b208f4728979a25b0d47e46d7b9d222"},"headline":"La patologia pelvica funzionale femminile &#8211; Ferrara &#8211; 26-27 gennaio 2018","datePublished":"2018-03-31T14:19:21+00:00","dateModified":"2019-01-24T15:16:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.zaccantispa.it\/en\/eventi-en\/la-patologia-pelvica-funzionale-femminile-ferrara-26-27-gennaio-2018\/"},"wordCount":16,"commentCount":0,"publisher":{"@id":"https:\/\/www.zaccantispa.it\/en\/#organization"},"image":{"@id":"https:\/\/www.zaccantispa.it\/en\/eventi-en\/la-patologia-pelvica-funzionale-femminile-ferrara-26-27-gennaio-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zaccantispa.it\/wp-content\/uploads\/2018\/03\/ferrara01.jpg","articleSection":["Eventi"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.zaccantispa.it\/en\/eventi-en\/la-patologia-pelvica-funzionale-femminile-ferrara-26-27-gennaio-2018\/","url":"https:\/\/www.zaccantispa.it\/en\/eventi-en\/la-patologia-pelvica-funzionale-femminile-ferrara-26-27-gennaio-2018\/","name":"La patologia pelvica funzionale femminile - Ferrara - 26-27 gennaio 2018 - Zaccanti S.p.A.","isPartOf":{"@id":"https:\/\/www.zaccantispa.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.zaccantispa.it\/en\/eventi-en\/la-patologia-pelvica-funzionale-femminile-ferrara-26-27-gennaio-2018\/#primaryimage"},"image":{"@id":"https:\/\/www.zaccantispa.it\/en\/eventi-en\/la-patologia-pelvica-funzionale-femminile-ferrara-26-27-gennaio-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zaccantispa.it\/wp-content\/uploads\/2018\/03\/ferrara01.jpg","datePublished":"2018-03-31T14:19:21+00:00","dateModified":"2019-01-24T15:16:57+00:00","breadcrumb":{"@id":"https:\/\/www.zaccantispa.it\/en\/eventi-en\/la-patologia-pelvica-funzionale-femminile-ferrara-26-27-gennaio-2018\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.zaccantispa.it\/en\/eventi-en\/la-patologia-pelvica-funzionale-femminile-ferrara-26-27-gennaio-2018\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.zaccantispa.it\/en\/eventi-en\/la-patologia-pelvica-funzionale-femminile-ferrara-26-27-gennaio-2018\/#primaryimage","url":"https:\/\/www.zaccantispa.it\/wp-content\/uploads\/2018\/03\/ferrara01.jpg","contentUrl":"https:\/\/www.zaccantispa.it\/wp-content\/uploads\/2018\/03\/ferrara01.jpg","width":745,"height":745},{"@type":"BreadcrumbList","@id":"https:\/\/www.zaccantispa.it\/en\/eventi-en\/la-patologia-pelvica-funzionale-femminile-ferrara-26-27-gennaio-2018\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.zaccantispa.it\/en\/"},{"@type":"ListItem","position":2,"name":"La patologia pelvica funzionale femminile &#8211; Ferrara &#8211; 26-27 gennaio 2018"}]},{"@type":"WebSite","@id":"https:\/\/www.zaccantispa.it\/en\/#website","url":"https:\/\/www.zaccantispa.it\/en\/","name":"Zaccanti S.p.A.","description":"La chirurgia esplora nuovi mondi","publisher":{"@id":"https:\/\/www.zaccantispa.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.zaccantispa.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.zaccantispa.it\/en\/#organization","name":"Zaccanti s.p.a.","url":"https:\/\/www.zaccantispa.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.zaccantispa.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.zaccantispa.it\/wp-content\/uploads\/2024\/05\/cropped-2024-02-14-Zaccanti-Bocchetti-Group-70-1954-2024-su-fondo-bianco-logo.png","contentUrl":"https:\/\/www.zaccantispa.it\/wp-content\/uploads\/2024\/05\/cropped-2024-02-14-Zaccanti-Bocchetti-Group-70-1954-2024-su-fondo-bianco-logo.png","width":512,"height":512,"caption":"Zaccanti s.p.a."},"image":{"@id":"https:\/\/www.zaccantispa.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ZaccantiSpABologna","https:\/\/www.linkedin.com\/company\/zaccanti-s-p-a\/"]},{"@type":"Person","@id":"https:\/\/www.zaccantispa.it\/en\/#\/schema\/person\/3b208f4728979a25b0d47e46d7b9d222","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/cb509eb6c091c3da64982812cd5189030e59b0d67219720a307a30a4f8d67560?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cb509eb6c091c3da64982812cd5189030e59b0d67219720a307a30a4f8d67560?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cb509eb6c091c3da64982812cd5189030e59b0d67219720a307a30a4f8d67560?s=96&d=mm&r=g","caption":"admin"}}]}},"_links":{"self":[{"href":"https:\/\/www.zaccantispa.it\/en\/wp-json\/wp\/v2\/posts\/2745","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zaccantispa.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zaccantispa.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zaccantispa.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zaccantispa.it\/en\/wp-json\/wp\/v2\/comments?post=2745"}],"version-history":[{"count":1,"href":"https:\/\/www.zaccantispa.it\/en\/wp-json\/wp\/v2\/posts\/2745\/revisions"}],"predecessor-version":[{"id":2746,"href":"https:\/\/www.zaccantispa.it\/en\/wp-json\/wp\/v2\/posts\/2745\/revisions\/2746"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zaccantispa.it\/en\/wp-json\/wp\/v2\/media\/1266"}],"wp:attachment":[{"href":"https:\/\/www.zaccantispa.it\/en\/wp-json\/wp\/v2\/media?parent=2745"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zaccantispa.it\/en\/wp-json\/wp\/v2\/categories?post=2745"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zaccantispa.it\/en\/wp-json\/wp\/v2\/tags?post=2745"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}