{"id":4710,"date":"2022-05-30T11:55:10","date_gmt":"2022-05-30T09:55:10","guid":{"rendered":"https:\/\/www.zaccantispa.it\/?p=4710"},"modified":"2022-05-30T11:55:10","modified_gmt":"2022-05-30T09:55:10","slug":"12th-15th-june-2022-aiic-riccione","status":"publish","type":"post","link":"https:\/\/www.zaccantispa.it\/en\/eventi-en\/12th-15th-june-2022-aiic-riccione\/","title":{"rendered":"12th-15th June 2022 &#8211; AIIC Riccione"},"content":{"rendered":"<p><a href=\"https:\/\/www.zaccantispa.it\/wp-content\/uploads\/2022\/05\/AIICRICCIONE2022-2.jpg\">View the flyer<\/a><\/p>\n<p><a href=\"https:\/\/www.aiic.it\/convegno-aiic-2022-oltre-il-pnrr-verso-una-cultura-tecnologica-a-sostegno-della-salute\/\">Visit the website<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>View the flyer Visit the website<\/p>\n","protected":false},"author":1,"featured_media":4716,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[71,72,48],"class_list":["post-4710","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi-en","tag-fegato-en","tag-mils-en","tag-scuola-en"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>12th-15th June 2022 - AIIC Riccione - Zaccanti S.p.A.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.zaccantispa.it\/en\/eventi-en\/12th-15th-june-2022-aiic-riccione\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"12th-15th June 2022 - AIIC Riccione - Zaccanti S.p.A.\" \/>\n<meta property=\"og:description\" content=\"View the flyer Visit the website\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.zaccantispa.it\/en\/eventi-en\/12th-15th-june-2022-aiic-riccione\/\" \/>\n<meta property=\"og:site_name\" content=\"Zaccanti S.p.A.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ZaccantiSpABologna\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-30T09:55:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.zaccantispa.it\/wp-content\/uploads\/2022\/05\/AIICRICCIONE2022.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1654\" \/>\n\t<meta property=\"og:image:height\" content=\"1114\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/eventi-en\\\/12th-15th-june-2022-aiic-riccione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/eventi-en\\\/12th-15th-june-2022-aiic-riccione\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/#\\\/schema\\\/person\\\/3b208f4728979a25b0d47e46d7b9d222\"},\"headline\":\"12th-15th June 2022 &#8211; AIIC Riccione\",\"datePublished\":\"2022-05-30T09:55:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/eventi-en\\\/12th-15th-june-2022-aiic-riccione\\\/\"},\"wordCount\":12,\"publisher\":{\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/eventi-en\\\/12th-15th-june-2022-aiic-riccione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zaccantispa.it\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/AIICRICCIONE2022.jpg\",\"keywords\":[\"fegato\",\"mils\",\"scuola\"],\"articleSection\":[\"Eventi\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/eventi-en\\\/12th-15th-june-2022-aiic-riccione\\\/\",\"url\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/eventi-en\\\/12th-15th-june-2022-aiic-riccione\\\/\",\"name\":\"12th-15th June 2022 - AIIC Riccione - Zaccanti S.p.A.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/eventi-en\\\/12th-15th-june-2022-aiic-riccione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/eventi-en\\\/12th-15th-june-2022-aiic-riccione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zaccantispa.it\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/AIICRICCIONE2022.jpg\",\"datePublished\":\"2022-05-30T09:55:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/eventi-en\\\/12th-15th-june-2022-aiic-riccione\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/eventi-en\\\/12th-15th-june-2022-aiic-riccione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/eventi-en\\\/12th-15th-june-2022-aiic-riccione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.zaccantispa.it\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/AIICRICCIONE2022.jpg\",\"contentUrl\":\"https:\\\/\\\/www.zaccantispa.it\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/AIICRICCIONE2022.jpg\",\"width\":1654,\"height\":1114},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/eventi-en\\\/12th-15th-june-2022-aiic-riccione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"12th-15th June 2022 &#8211; AIIC Riccione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/\",\"name\":\"Zaccanti S.p.A.\",\"description\":\"La chirurgia esplora nuovi mondi\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/#organization\",\"name\":\"Zaccanti s.p.a.\",\"url\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.zaccantispa.it\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-2024-02-14-Zaccanti-Bocchetti-Group-70-1954-2024-su-fondo-bianco-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.zaccantispa.it\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-2024-02-14-Zaccanti-Bocchetti-Group-70-1954-2024-su-fondo-bianco-logo.png\",\"width\":512,\"height\":512,\"caption\":\"Zaccanti s.p.a.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ZaccantiSpABologna\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/zaccanti-s-p-a\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/#\\\/schema\\\/person\\\/3b208f4728979a25b0d47e46d7b9d222\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cb509eb6c091c3da64982812cd5189030e59b0d67219720a307a30a4f8d67560?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cb509eb6c091c3da64982812cd5189030e59b0d67219720a307a30a4f8d67560?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cb509eb6c091c3da64982812cd5189030e59b0d67219720a307a30a4f8d67560?s=96&d=mm&r=g\",\"caption\":\"admin\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"12th-15th June 2022 - AIIC Riccione - Zaccanti S.p.A.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.zaccantispa.it\/en\/eventi-en\/12th-15th-june-2022-aiic-riccione\/","og_locale":"en_US","og_type":"article","og_title":"12th-15th June 2022 - AIIC Riccione - Zaccanti S.p.A.","og_description":"View the flyer Visit the website","og_url":"https:\/\/www.zaccantispa.it\/en\/eventi-en\/12th-15th-june-2022-aiic-riccione\/","og_site_name":"Zaccanti S.p.A.","article_publisher":"https:\/\/www.facebook.com\/ZaccantiSpABologna","article_published_time":"2022-05-30T09:55:10+00:00","og_image":[{"width":1654,"height":1114,"url":"https:\/\/www.zaccantispa.it\/wp-content\/uploads\/2022\/05\/AIICRICCIONE2022.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.zaccantispa.it\/en\/eventi-en\/12th-15th-june-2022-aiic-riccione\/#article","isPartOf":{"@id":"https:\/\/www.zaccantispa.it\/en\/eventi-en\/12th-15th-june-2022-aiic-riccione\/"},"author":{"name":"admin","@id":"https:\/\/www.zaccantispa.it\/en\/#\/schema\/person\/3b208f4728979a25b0d47e46d7b9d222"},"headline":"12th-15th June 2022 &#8211; AIIC Riccione","datePublished":"2022-05-30T09:55:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.zaccantispa.it\/en\/eventi-en\/12th-15th-june-2022-aiic-riccione\/"},"wordCount":12,"publisher":{"@id":"https:\/\/www.zaccantispa.it\/en\/#organization"},"image":{"@id":"https:\/\/www.zaccantispa.it\/en\/eventi-en\/12th-15th-june-2022-aiic-riccione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zaccantispa.it\/wp-content\/uploads\/2022\/05\/AIICRICCIONE2022.jpg","keywords":["fegato","mils","scuola"],"articleSection":["Eventi"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.zaccantispa.it\/en\/eventi-en\/12th-15th-june-2022-aiic-riccione\/","url":"https:\/\/www.zaccantispa.it\/en\/eventi-en\/12th-15th-june-2022-aiic-riccione\/","name":"12th-15th June 2022 - AIIC Riccione - Zaccanti S.p.A.","isPartOf":{"@id":"https:\/\/www.zaccantispa.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.zaccantispa.it\/en\/eventi-en\/12th-15th-june-2022-aiic-riccione\/#primaryimage"},"image":{"@id":"https:\/\/www.zaccantispa.it\/en\/eventi-en\/12th-15th-june-2022-aiic-riccione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zaccantispa.it\/wp-content\/uploads\/2022\/05\/AIICRICCIONE2022.jpg","datePublished":"2022-05-30T09:55:10+00:00","breadcrumb":{"@id":"https:\/\/www.zaccantispa.it\/en\/eventi-en\/12th-15th-june-2022-aiic-riccione\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.zaccantispa.it\/en\/eventi-en\/12th-15th-june-2022-aiic-riccione\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.zaccantispa.it\/en\/eventi-en\/12th-15th-june-2022-aiic-riccione\/#primaryimage","url":"https:\/\/www.zaccantispa.it\/wp-content\/uploads\/2022\/05\/AIICRICCIONE2022.jpg","contentUrl":"https:\/\/www.zaccantispa.it\/wp-content\/uploads\/2022\/05\/AIICRICCIONE2022.jpg","width":1654,"height":1114},{"@type":"BreadcrumbList","@id":"https:\/\/www.zaccantispa.it\/en\/eventi-en\/12th-15th-june-2022-aiic-riccione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.zaccantispa.it\/en\/"},{"@type":"ListItem","position":2,"name":"12th-15th June 2022 &#8211; AIIC Riccione"}]},{"@type":"WebSite","@id":"https:\/\/www.zaccantispa.it\/en\/#website","url":"https:\/\/www.zaccantispa.it\/en\/","name":"Zaccanti S.p.A.","description":"La chirurgia esplora nuovi mondi","publisher":{"@id":"https:\/\/www.zaccantispa.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.zaccantispa.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.zaccantispa.it\/en\/#organization","name":"Zaccanti s.p.a.","url":"https:\/\/www.zaccantispa.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.zaccantispa.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.zaccantispa.it\/wp-content\/uploads\/2024\/05\/cropped-2024-02-14-Zaccanti-Bocchetti-Group-70-1954-2024-su-fondo-bianco-logo.png","contentUrl":"https:\/\/www.zaccantispa.it\/wp-content\/uploads\/2024\/05\/cropped-2024-02-14-Zaccanti-Bocchetti-Group-70-1954-2024-su-fondo-bianco-logo.png","width":512,"height":512,"caption":"Zaccanti s.p.a."},"image":{"@id":"https:\/\/www.zaccantispa.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ZaccantiSpABologna","https:\/\/www.linkedin.com\/company\/zaccanti-s-p-a\/"]},{"@type":"Person","@id":"https:\/\/www.zaccantispa.it\/en\/#\/schema\/person\/3b208f4728979a25b0d47e46d7b9d222","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/cb509eb6c091c3da64982812cd5189030e59b0d67219720a307a30a4f8d67560?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cb509eb6c091c3da64982812cd5189030e59b0d67219720a307a30a4f8d67560?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cb509eb6c091c3da64982812cd5189030e59b0d67219720a307a30a4f8d67560?s=96&d=mm&r=g","caption":"admin"}}]}},"_links":{"self":[{"href":"https:\/\/www.zaccantispa.it\/en\/wp-json\/wp\/v2\/posts\/4710","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zaccantispa.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zaccantispa.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zaccantispa.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zaccantispa.it\/en\/wp-json\/wp\/v2\/comments?post=4710"}],"version-history":[{"count":1,"href":"https:\/\/www.zaccantispa.it\/en\/wp-json\/wp\/v2\/posts\/4710\/revisions"}],"predecessor-version":[{"id":4719,"href":"https:\/\/www.zaccantispa.it\/en\/wp-json\/wp\/v2\/posts\/4710\/revisions\/4719"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zaccantispa.it\/en\/wp-json\/wp\/v2\/media\/4716"}],"wp:attachment":[{"href":"https:\/\/www.zaccantispa.it\/en\/wp-json\/wp\/v2\/media?parent=4710"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zaccantispa.it\/en\/wp-json\/wp\/v2\/categories?post=4710"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zaccantispa.it\/en\/wp-json\/wp\/v2\/tags?post=4710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}