{"id":5804,"date":"2024-11-26T12:47:51","date_gmt":"2024-11-26T11:47:51","guid":{"rendered":"https:\/\/www.zaccantispa.it\/?p=5804"},"modified":"2024-11-27T11:11:45","modified_gmt":"2024-11-27T10:11:45","slug":"november-28-2024-piacenza-airways-management-day","status":"publish","type":"post","link":"https:\/\/www.zaccantispa.it\/en\/eventi-en\/november-28-2024-piacenza-airways-management-day\/","title":{"rendered":"November 28, 2024 \u2013 Piacenza Airways Management Day"},"content":{"rendered":"<p><a href=\"https:\/\/www.zaccantispa.it\/wp-content\/uploads\/2024\/11\/Programma-PAMD.pdf\" target=\"_blank\" rel=\"noopener\">View the program<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>View the program<\/p>\n","protected":false},"author":1,"featured_media":5829,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-5804","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi-en"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>November 28, 2024 \u2013 Piacenza Airways Management Day - Zaccanti S.p.A.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.zaccantispa.it\/en\/eventi-en\/november-28-2024-piacenza-airways-management-day\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"November 28, 2024 \u2013 Piacenza Airways Management Day - Zaccanti S.p.A.\" \/>\n<meta property=\"og:description\" content=\"View the program\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.zaccantispa.it\/en\/eventi-en\/november-28-2024-piacenza-airways-management-day\/\" \/>\n<meta property=\"og:site_name\" content=\"Zaccanti S.p.A.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ZaccantiSpABologna\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-26T11:47:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-27T10:11:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.zaccantispa.it\/wp-content\/uploads\/2024\/11\/Schermata-2024-11-26-alle-12.43.53-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1906\" \/>\n\t<meta property=\"og:image:height\" content=\"2716\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/eventi-en\\\/november-28-2024-piacenza-airways-management-day\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/eventi-en\\\/november-28-2024-piacenza-airways-management-day\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/#\\\/schema\\\/person\\\/3b208f4728979a25b0d47e46d7b9d222\"},\"headline\":\"November 28, 2024 \u2013 Piacenza Airways Management Day\",\"datePublished\":\"2024-11-26T11:47:51+00:00\",\"dateModified\":\"2024-11-27T10:11:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/eventi-en\\\/november-28-2024-piacenza-airways-management-day\\\/\"},\"wordCount\":8,\"publisher\":{\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/eventi-en\\\/november-28-2024-piacenza-airways-management-day\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zaccantispa.it\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Schermata-2024-11-26-alle-12.43.53-2.png\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/eventi-en\\\/november-28-2024-piacenza-airways-management-day\\\/\",\"url\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/eventi-en\\\/november-28-2024-piacenza-airways-management-day\\\/\",\"name\":\"November 28, 2024 \u2013 Piacenza Airways Management Day - Zaccanti S.p.A.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/eventi-en\\\/november-28-2024-piacenza-airways-management-day\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/eventi-en\\\/november-28-2024-piacenza-airways-management-day\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zaccantispa.it\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Schermata-2024-11-26-alle-12.43.53-2.png\",\"datePublished\":\"2024-11-26T11:47:51+00:00\",\"dateModified\":\"2024-11-27T10:11:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/eventi-en\\\/november-28-2024-piacenza-airways-management-day\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/eventi-en\\\/november-28-2024-piacenza-airways-management-day\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/eventi-en\\\/november-28-2024-piacenza-airways-management-day\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.zaccantispa.it\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Schermata-2024-11-26-alle-12.43.53-2.png\",\"contentUrl\":\"https:\\\/\\\/www.zaccantispa.it\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Schermata-2024-11-26-alle-12.43.53-2.png\",\"width\":1906,\"height\":2716},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/eventi-en\\\/november-28-2024-piacenza-airways-management-day\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"November 28, 2024 \u2013 Piacenza Airways Management Day\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/\",\"name\":\"Zaccanti S.p.A.\",\"description\":\"La chirurgia esplora nuovi mondi\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/#organization\",\"name\":\"Zaccanti s.p.a.\",\"url\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.zaccantispa.it\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-2024-02-14-Zaccanti-Bocchetti-Group-70-1954-2024-su-fondo-bianco-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.zaccantispa.it\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-2024-02-14-Zaccanti-Bocchetti-Group-70-1954-2024-su-fondo-bianco-logo.png\",\"width\":512,\"height\":512,\"caption\":\"Zaccanti s.p.a.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ZaccantiSpABologna\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/zaccanti-s-p-a\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.zaccantispa.it\\\/en\\\/#\\\/schema\\\/person\\\/3b208f4728979a25b0d47e46d7b9d222\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cb509eb6c091c3da64982812cd5189030e59b0d67219720a307a30a4f8d67560?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cb509eb6c091c3da64982812cd5189030e59b0d67219720a307a30a4f8d67560?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cb509eb6c091c3da64982812cd5189030e59b0d67219720a307a30a4f8d67560?s=96&d=mm&r=g\",\"caption\":\"admin\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"November 28, 2024 \u2013 Piacenza Airways Management Day - Zaccanti S.p.A.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.zaccantispa.it\/en\/eventi-en\/november-28-2024-piacenza-airways-management-day\/","og_locale":"en_US","og_type":"article","og_title":"November 28, 2024 \u2013 Piacenza Airways Management Day - Zaccanti S.p.A.","og_description":"View the program","og_url":"https:\/\/www.zaccantispa.it\/en\/eventi-en\/november-28-2024-piacenza-airways-management-day\/","og_site_name":"Zaccanti S.p.A.","article_publisher":"https:\/\/www.facebook.com\/ZaccantiSpABologna","article_published_time":"2024-11-26T11:47:51+00:00","article_modified_time":"2024-11-27T10:11:45+00:00","og_image":[{"width":1906,"height":2716,"url":"https:\/\/www.zaccantispa.it\/wp-content\/uploads\/2024\/11\/Schermata-2024-11-26-alle-12.43.53-2.png","type":"image\/png"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.zaccantispa.it\/en\/eventi-en\/november-28-2024-piacenza-airways-management-day\/#article","isPartOf":{"@id":"https:\/\/www.zaccantispa.it\/en\/eventi-en\/november-28-2024-piacenza-airways-management-day\/"},"author":{"name":"admin","@id":"https:\/\/www.zaccantispa.it\/en\/#\/schema\/person\/3b208f4728979a25b0d47e46d7b9d222"},"headline":"November 28, 2024 \u2013 Piacenza Airways Management Day","datePublished":"2024-11-26T11:47:51+00:00","dateModified":"2024-11-27T10:11:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.zaccantispa.it\/en\/eventi-en\/november-28-2024-piacenza-airways-management-day\/"},"wordCount":8,"publisher":{"@id":"https:\/\/www.zaccantispa.it\/en\/#organization"},"image":{"@id":"https:\/\/www.zaccantispa.it\/en\/eventi-en\/november-28-2024-piacenza-airways-management-day\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zaccantispa.it\/wp-content\/uploads\/2024\/11\/Schermata-2024-11-26-alle-12.43.53-2.png","articleSection":["Eventi"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.zaccantispa.it\/en\/eventi-en\/november-28-2024-piacenza-airways-management-day\/","url":"https:\/\/www.zaccantispa.it\/en\/eventi-en\/november-28-2024-piacenza-airways-management-day\/","name":"November 28, 2024 \u2013 Piacenza Airways Management Day - Zaccanti S.p.A.","isPartOf":{"@id":"https:\/\/www.zaccantispa.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.zaccantispa.it\/en\/eventi-en\/november-28-2024-piacenza-airways-management-day\/#primaryimage"},"image":{"@id":"https:\/\/www.zaccantispa.it\/en\/eventi-en\/november-28-2024-piacenza-airways-management-day\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zaccantispa.it\/wp-content\/uploads\/2024\/11\/Schermata-2024-11-26-alle-12.43.53-2.png","datePublished":"2024-11-26T11:47:51+00:00","dateModified":"2024-11-27T10:11:45+00:00","breadcrumb":{"@id":"https:\/\/www.zaccantispa.it\/en\/eventi-en\/november-28-2024-piacenza-airways-management-day\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.zaccantispa.it\/en\/eventi-en\/november-28-2024-piacenza-airways-management-day\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.zaccantispa.it\/en\/eventi-en\/november-28-2024-piacenza-airways-management-day\/#primaryimage","url":"https:\/\/www.zaccantispa.it\/wp-content\/uploads\/2024\/11\/Schermata-2024-11-26-alle-12.43.53-2.png","contentUrl":"https:\/\/www.zaccantispa.it\/wp-content\/uploads\/2024\/11\/Schermata-2024-11-26-alle-12.43.53-2.png","width":1906,"height":2716},{"@type":"BreadcrumbList","@id":"https:\/\/www.zaccantispa.it\/en\/eventi-en\/november-28-2024-piacenza-airways-management-day\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.zaccantispa.it\/en\/"},{"@type":"ListItem","position":2,"name":"November 28, 2024 \u2013 Piacenza Airways Management Day"}]},{"@type":"WebSite","@id":"https:\/\/www.zaccantispa.it\/en\/#website","url":"https:\/\/www.zaccantispa.it\/en\/","name":"Zaccanti S.p.A.","description":"La chirurgia esplora nuovi mondi","publisher":{"@id":"https:\/\/www.zaccantispa.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.zaccantispa.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.zaccantispa.it\/en\/#organization","name":"Zaccanti s.p.a.","url":"https:\/\/www.zaccantispa.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.zaccantispa.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.zaccantispa.it\/wp-content\/uploads\/2024\/05\/cropped-2024-02-14-Zaccanti-Bocchetti-Group-70-1954-2024-su-fondo-bianco-logo.png","contentUrl":"https:\/\/www.zaccantispa.it\/wp-content\/uploads\/2024\/05\/cropped-2024-02-14-Zaccanti-Bocchetti-Group-70-1954-2024-su-fondo-bianco-logo.png","width":512,"height":512,"caption":"Zaccanti s.p.a."},"image":{"@id":"https:\/\/www.zaccantispa.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ZaccantiSpABologna","https:\/\/www.linkedin.com\/company\/zaccanti-s-p-a\/"]},{"@type":"Person","@id":"https:\/\/www.zaccantispa.it\/en\/#\/schema\/person\/3b208f4728979a25b0d47e46d7b9d222","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/cb509eb6c091c3da64982812cd5189030e59b0d67219720a307a30a4f8d67560?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cb509eb6c091c3da64982812cd5189030e59b0d67219720a307a30a4f8d67560?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cb509eb6c091c3da64982812cd5189030e59b0d67219720a307a30a4f8d67560?s=96&d=mm&r=g","caption":"admin"}}]}},"_links":{"self":[{"href":"https:\/\/www.zaccantispa.it\/en\/wp-json\/wp\/v2\/posts\/5804","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zaccantispa.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zaccantispa.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zaccantispa.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zaccantispa.it\/en\/wp-json\/wp\/v2\/comments?post=5804"}],"version-history":[{"count":1,"href":"https:\/\/www.zaccantispa.it\/en\/wp-json\/wp\/v2\/posts\/5804\/revisions"}],"predecessor-version":[{"id":5816,"href":"https:\/\/www.zaccantispa.it\/en\/wp-json\/wp\/v2\/posts\/5804\/revisions\/5816"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zaccantispa.it\/en\/wp-json\/wp\/v2\/media\/5829"}],"wp:attachment":[{"href":"https:\/\/www.zaccantispa.it\/en\/wp-json\/wp\/v2\/media?parent=5804"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zaccantispa.it\/en\/wp-json\/wp\/v2\/categories?post=5804"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zaccantispa.it\/en\/wp-json\/wp\/v2\/tags?post=5804"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}